{"id":1925,"date":"2026-08-27T22:41:12","date_gmt":"2026-08-27T22:41:12","guid":{"rendered":"https:\/\/mxenes.cl\/home\/?p=1925"},"modified":"2026-09-01T22:58:49","modified_gmt":"2026-09-01T22:58:49","slug":"amxsa-acerca-la-nanotecnologia-a-ninas-y-jovenes","status":"publish","type":"post","link":"https:\/\/mxenes.cl\/home\/amxsa-acerca-la-nanotecnologia-a-ninas-y-jovenes\/","title":{"rendered":"AMXSA acerca la nanotecnolog\u00eda a ni\u00f1as y j\u00f3venes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un equipo del N\u00facleo Milenio de MXenos Avanzados para Aplicaciones en Sustentabilidad (AMXSA) realiz\u00f3 un Taller de Nanotecnolog\u00eda dirigido a 30 ni\u00f1as y j\u00f3venes, con el prop\u00f3sito de acercarlas a la ciencia de materiales y mostrarles algunas de sus aplicaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad form\u00f3 parte de una jornada destinada a acercar las ciencias, la tecnolog\u00eda, la ingenier\u00eda y las matem\u00e1ticas (STEM) a m\u00e1s de 300 estudiantes de distintos establecimientos educacionales de la Regi\u00f3n Metropolitana. La iniciativa fue organizada por la Direcci\u00f3n de Diversidad y G\u00e9nero y el \u00c1rea de Difusi\u00f3n a Colegios de la Facultad de Ciencias F\u00edsicas y Matem\u00e1ticas de la Universidad de Chile, en colaboraci\u00f3n con la Fundaci\u00f3n Pi\u00f1era Morel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La convocatoria reuni\u00f3 a estudiantes de Liceos Bicentenario, adem\u00e1s del Centro Educacional Municipal Dr. Amador Neghme Rodr\u00edguez, de Estaci\u00f3n Central, y la Escuela Primitiva Echeverr\u00eda, de Quilicura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada comenz\u00f3 con la charla \u201cAgujeros negros, planetas y galaxias, descubriendo el universo desde Chile\u201d, dictada por la astr\u00f3noma, divulgadora cient\u00edfica y exalumna de la FCFM Tere Paneque. Posteriormente, las estudiantes recorrieron el Campus Beauchef y participaron en talleres pr\u00e1cticos vinculados con diferentes \u00e1reas cient\u00edficas y tecnol\u00f3gicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La nanotecnolog\u00eda desde la vida cotidiana<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Taller de Nanotecnolog\u00eda fue impartido por un equipo de AMXSA integrado por \u00c1lvaro Correa, Iasi Cervantes, Roc\u00edo Marcoleta, Ignacio Illanes, Daniela Lizama, Fabi\u00e1n Flores, Javier Marques, Nicol\u00e1s Bustos y Andreas Rosenkranz, director del N\u00facleo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la actividad, las estudiantes conocieron las propiedades de distintos materiales y algunas de sus aplicaciones. A trav\u00e9s de experiencias pr\u00e1cticas y ejemplos vinculados con la vida cotidiana, pudieron acercarse a la nanotecnolog\u00eda y descubrir c\u00f3mo la ciencia de materiales puede aportar al desarrollo de soluciones para desaf\u00edos medioambientales, m\u00e9dicos y log\u00edsticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Iasi Cervantes, investigadora de AMXSA y una de las integrantes del equipo que desarroll\u00f3 el taller, destac\u00f3 la importancia de generar espacios de motivaci\u00f3n para ni\u00f1as y j\u00f3venes. \u201cEn un contexto en que las mujeres y las ni\u00f1as han estado subrepresentadas en los espacios de ciencia, tecnolog\u00eda e ingenier\u00eda, me parece muy relevante generar instancias que las motiven. Este taller permiti\u00f3 acercarlas a la ciencia de una manera sencilla y a partir de la vida cotidiana, y esperamos tambi\u00e9n haberlas inspirado\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La investigadora tambi\u00e9n valor\u00f3 el inter\u00e9s demostrado por las participantes. \u201cFue una jornada muy exitosa. Las vimos muy participativas, llev\u00e1ndose regalos y experiencias muy lindas del taller. Espero que algo de lo vivido se quede en sus corazones\u201d, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Andreas Rosenkranz destac\u00f3 la importancia de la difusi\u00f3n cient\u00edfica para vincular el trabajo de AMXSA con la sociedad. \u201cLa difusi\u00f3n cient\u00edfica es una parte fundamental de nuestro trabajo, porque nos permite compartir el conocimiento que generamos y mostrar c\u00f3mo la ciencia puede contribuir a resolver problemas concretos. Acercar la nanotecnolog\u00eda a ni\u00f1as y j\u00f3venes mediante experiencias pr\u00e1cticas tambi\u00e9n puede despertar su curiosidad, ampliar sus posibilidades e inspirarlas a proyectarse en \u00e1reas cient\u00edficas y tecnol\u00f3gicas\u201d, afirm\u00f3 el director del N\u00facleo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La participaci\u00f3n de AMXSA permiti\u00f3 vincular la investigaci\u00f3n desarrollada en la Universidad de Chile con una experiencia pr\u00e1ctica, acercar la nanotecnolog\u00eda a estudiantes de ense\u00f1anza media y mostrarles referentes femeninos en el \u00e1mbito de la ciencia y la ingenier\u00eda. Asimismo, la actividad reafirm\u00f3 la importancia de la difusi\u00f3n cient\u00edfica para compartir el conocimiento m\u00e1s all\u00e1 de los espacios acad\u00e9micos y contribuir a despertar nuevas vocaciones.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"1927\" src=\"https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/1-1024x768.jpeg\" alt=\"\" class=\"wp-image-1927\" srcset=\"https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/1-1024x768.jpeg 1024w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/1-768x576.jpeg 768w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/1-300x225.jpeg 300w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/1-16x12.jpeg 16w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"1931\" src=\"https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/4-1024x768.jpg\" alt=\"\" class=\"wp-image-1931\" srcset=\"https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/4-1024x768.jpg 1024w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/4-300x225.jpg 300w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/4-768x576.jpg 768w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/4-16x12.jpg 16w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/4.jpg 1290w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"866\" height=\"649\" data-id=\"1928\" src=\"https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/3.jpeg\" alt=\"\" class=\"wp-image-1928\" srcset=\"https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/3.jpeg 866w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/3-300x225.jpeg 300w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/3-767x575.jpeg 767w, https:\/\/mxenes.cl\/home\/wp-content\/uploads\/2026\/09\/3-16x12.jpeg 16w\" sizes=\"(max-width: 866px) 100vw, 866px\" \/><\/figure>\n\n\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Las estudiantes participaron en un taller pr\u00e1ctico que les permiti\u00f3 conocer c\u00f3mo la ciencia de materiales puede contribuir a enfrentar distintos desaf\u00edos de la sociedad.<\/p>\n","protected":false},"author":3,"featured_media":1926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/posts\/1925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/comments?post=1925"}],"version-history":[{"count":2,"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/posts\/1925\/revisions"}],"predecessor-version":[{"id":1932,"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/posts\/1925\/revisions\/1932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/media\/1926"}],"wp:attachment":[{"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/media?parent=1925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/categories?post=1925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mxenes.cl\/home\/wp-json\/wp\/v2\/tags?post=1925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}